{"id":11874,"count":22,"description":"<h1><strong>Slidekamera Camera Slider<\/strong><\/h1>","link":"https:\/\/cinegear.nl\/tr\/brand\/slidekamera\/","name":"Slidekamera","slug":"slidekamera","taxonomy":"pwb-brand","parent":0,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v21.8 (Yoast SEO v24.3) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Slidekamera | Cinegear Amsterdam<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cinegear.nl\/tr\/brand\/slidekamera\/\" \/>\n<meta property=\"og:locale\" content=\"tr_TR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Slidekamera\" \/>\n<meta property=\"og:description\" content=\"Slidekamera Camera Slider\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cinegear.nl\/tr\/brand\/slidekamera\/\" \/>\n<meta property=\"og:site_name\" content=\"Cinegear Amsterdam\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/cinegear.nl\/brand\/slidekamera\/\",\"url\":\"https:\/\/cinegear.nl\/brand\/slidekamera\/\",\"name\":\"Slidekamera | Cinegear Amsterdam\",\"isPartOf\":{\"@id\":\"https:\/\/cinegear.nl\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/cinegear.nl\/brand\/slidekamera\/#breadcrumb\"},\"inLanguage\":\"tr\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/cinegear.nl\/brand\/slidekamera\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/cinegear.nl\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Slidekamera\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/cinegear.nl\/#website\",\"url\":\"https:\/\/cinegear.nl\/\",\"name\":\"Cinegear Amsterdam\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/cinegear.nl\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/cinegear.nl\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"tr\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/cinegear.nl\/#organization\",\"name\":\"Cinegear\",\"url\":\"https:\/\/cinegear.nl\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"tr\",\"@id\":\"https:\/\/cinegear.nl\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/cinegear.nl\/wp-content\/uploads\/2019\/12\/Transparent_Normal_Logo.jpg\",\"contentUrl\":\"https:\/\/cinegear.nl\/wp-content\/uploads\/2019\/12\/Transparent_Normal_Logo.jpg\",\"width\":858,\"height\":782,\"caption\":\"Cinegear\"},\"image\":{\"@id\":\"https:\/\/cinegear.nl\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Slidekamera | Cinegear Amsterdam","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cinegear.nl\/tr\/brand\/slidekamera\/","og_locale":"tr_TR","og_type":"article","og_title":"Slidekamera","og_description":"Slidekamera Camera Slider","og_url":"https:\/\/cinegear.nl\/tr\/brand\/slidekamera\/","og_site_name":"Cinegear Amsterdam","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/cinegear.nl\/brand\/slidekamera\/","url":"https:\/\/cinegear.nl\/brand\/slidekamera\/","name":"Slidekamera | Cinegear Amsterdam","isPartOf":{"@id":"https:\/\/cinegear.nl\/#website"},"breadcrumb":{"@id":"https:\/\/cinegear.nl\/brand\/slidekamera\/#breadcrumb"},"inLanguage":"tr"},{"@type":"BreadcrumbList","@id":"https:\/\/cinegear.nl\/brand\/slidekamera\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cinegear.nl\/"},{"@type":"ListItem","position":2,"name":"Slidekamera"}]},{"@type":"WebSite","@id":"https:\/\/cinegear.nl\/#website","url":"https:\/\/cinegear.nl\/","name":"Cinegear Amsterdam","description":"","publisher":{"@id":"https:\/\/cinegear.nl\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cinegear.nl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"tr"},{"@type":"Organization","@id":"https:\/\/cinegear.nl\/#organization","name":"Cinegear","url":"https:\/\/cinegear.nl\/","logo":{"@type":"ImageObject","inLanguage":"tr","@id":"https:\/\/cinegear.nl\/#\/schema\/logo\/image\/","url":"https:\/\/cinegear.nl\/wp-content\/uploads\/2019\/12\/Transparent_Normal_Logo.jpg","contentUrl":"https:\/\/cinegear.nl\/wp-content\/uploads\/2019\/12\/Transparent_Normal_Logo.jpg","width":858,"height":782,"caption":"Cinegear"},"image":{"@id":"https:\/\/cinegear.nl\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/cinegear.nl\/tr\/wp-json\/wp\/v2\/pwb-brand\/11874","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cinegear.nl\/tr\/wp-json\/wp\/v2\/pwb-brand"}],"about":[{"href":"https:\/\/cinegear.nl\/tr\/wp-json\/wp\/v2\/taxonomies\/pwb-brand"}],"wp:post_type":[{"href":"https:\/\/cinegear.nl\/tr\/wp-json\/wp\/v2\/product?pwb-brand=11874"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}