{"id":117430,"date":"2025-11-15T11:57:51","date_gmt":"2025-11-15T10:57:51","guid":{"rendered":"https:\/\/cinegear.nl\/?post_type=product&#038;p=117430"},"modified":"2026-04-23T06:39:56","modified_gmt":"2026-04-23T04:39:56","slug":"nanlux-lan-extension-adapter","status":"publish","type":"product","link":"https:\/\/cinegear.nl\/nl\/product\/nanlux-lan-extension-adapter\/","title":{"rendered":"Nanlux LAN Extension Adapter"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":117440,"template":"","meta":{"_acf_changed":false,"inline_featured_image":false},"pwb-brand":[10145],"product_cat":[1065],"product_tag":[],"class_list":{"0":"post-117430","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"pwb-brand-nanlux","7":"product_cat-light-accessoires","9":"first","10":"instock","11":"taxable","12":"shipping-taxable","13":"purchasable","14":"product-type-simple"},"acf":{"supplier":"EuropePV","buy_price":"110.8","last_sync":"2026-04-23"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v21.8 (Yoast SEO v24.3) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Nanlux LAN Extension Adapter | Cinegear Amsterdam<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cinegear.nl\/nl\/product\/nanlux-lan-extension-adapter\/\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nanlux LAN Extension Adapter\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cinegear.nl\/nl\/product\/nanlux-lan-extension-adapter\/\" \/>\n<meta property=\"og:site_name\" content=\"Cinegear Amsterdam\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-23T04:39:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cinegear.nl\/wp-content\/uploads\/2025\/11\/Nanlux-LAN-Extension-Adapter.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1850\" \/>\n\t<meta property=\"og:image:height\" content=\"1850\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/cinegear.nl\/product\/nanlux-lan-extension-adapter\/\",\"url\":\"https:\/\/cinegear.nl\/product\/nanlux-lan-extension-adapter\/\",\"name\":\"Nanlux LAN Extension Adapter | Cinegear Amsterdam\",\"isPartOf\":{\"@id\":\"https:\/\/cinegear.nl\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/cinegear.nl\/product\/nanlux-lan-extension-adapter\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/cinegear.nl\/product\/nanlux-lan-extension-adapter\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/cinegear.nl\/wp-content\/uploads\/2025\/11\/Nanlux-LAN-Extension-Adapter.jpg\",\"datePublished\":\"2025-11-15T10:57:51+00:00\",\"dateModified\":\"2026-04-23T04:39:56+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/cinegear.nl\/product\/nanlux-lan-extension-adapter\/#breadcrumb\"},\"inLanguage\":\"nl-NL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/cinegear.nl\/product\/nanlux-lan-extension-adapter\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\/\/cinegear.nl\/product\/nanlux-lan-extension-adapter\/#primaryimage\",\"url\":\"https:\/\/cinegear.nl\/wp-content\/uploads\/2025\/11\/Nanlux-LAN-Extension-Adapter.jpg\",\"contentUrl\":\"https:\/\/cinegear.nl\/wp-content\/uploads\/2025\/11\/Nanlux-LAN-Extension-Adapter.jpg\",\"width\":1850,\"height\":1850},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/cinegear.nl\/product\/nanlux-lan-extension-adapter\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/cinegear.nl\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Store\",\"item\":\"https:\/\/cinegear.nl\/product-category-kine-cameras\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Nanlux LAN Extension Adapter\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/cinegear.nl\/#website\",\"url\":\"https:\/\/cinegear.nl\/\",\"name\":\"Cinegear Amsterdam\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/cinegear.nl\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/cinegear.nl\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nl-NL\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/cinegear.nl\/#organization\",\"name\":\"Cinegear\",\"url\":\"https:\/\/cinegear.nl\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\/\/cinegear.nl\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/cinegear.nl\/wp-content\/uploads\/2019\/12\/Transparent_Normal_Logo.jpg\",\"contentUrl\":\"https:\/\/cinegear.nl\/wp-content\/uploads\/2019\/12\/Transparent_Normal_Logo.jpg\",\"width\":858,\"height\":782,\"caption\":\"Cinegear\"},\"image\":{\"@id\":\"https:\/\/cinegear.nl\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Nanlux LAN Extension Adapter | Cinegear Amsterdam","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cinegear.nl\/nl\/product\/nanlux-lan-extension-adapter\/","og_locale":"nl_NL","og_type":"article","og_title":"Nanlux LAN Extension Adapter","og_url":"https:\/\/cinegear.nl\/nl\/product\/nanlux-lan-extension-adapter\/","og_site_name":"Cinegear Amsterdam","article_modified_time":"2026-04-23T04:39:56+00:00","og_image":[{"width":1850,"height":1850,"url":"https:\/\/cinegear.nl\/wp-content\/uploads\/2025\/11\/Nanlux-LAN-Extension-Adapter.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/cinegear.nl\/product\/nanlux-lan-extension-adapter\/","url":"https:\/\/cinegear.nl\/product\/nanlux-lan-extension-adapter\/","name":"Nanlux LAN Extension Adapter | Cinegear Amsterdam","isPartOf":{"@id":"https:\/\/cinegear.nl\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cinegear.nl\/product\/nanlux-lan-extension-adapter\/#primaryimage"},"image":{"@id":"https:\/\/cinegear.nl\/product\/nanlux-lan-extension-adapter\/#primaryimage"},"thumbnailUrl":"https:\/\/cinegear.nl\/wp-content\/uploads\/2025\/11\/Nanlux-LAN-Extension-Adapter.jpg","datePublished":"2025-11-15T10:57:51+00:00","dateModified":"2026-04-23T04:39:56+00:00","breadcrumb":{"@id":"https:\/\/cinegear.nl\/product\/nanlux-lan-extension-adapter\/#breadcrumb"},"inLanguage":"nl-NL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cinegear.nl\/product\/nanlux-lan-extension-adapter\/"]}]},{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/cinegear.nl\/product\/nanlux-lan-extension-adapter\/#primaryimage","url":"https:\/\/cinegear.nl\/wp-content\/uploads\/2025\/11\/Nanlux-LAN-Extension-Adapter.jpg","contentUrl":"https:\/\/cinegear.nl\/wp-content\/uploads\/2025\/11\/Nanlux-LAN-Extension-Adapter.jpg","width":1850,"height":1850},{"@type":"BreadcrumbList","@id":"https:\/\/cinegear.nl\/product\/nanlux-lan-extension-adapter\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cinegear.nl\/"},{"@type":"ListItem","position":2,"name":"Store","item":"https:\/\/cinegear.nl\/product-category-kine-cameras\/"},{"@type":"ListItem","position":3,"name":"Nanlux LAN Extension Adapter"}]},{"@type":"WebSite","@id":"https:\/\/cinegear.nl\/#website","url":"https:\/\/cinegear.nl\/","name":"Cinegear Amsterdam","description":"","publisher":{"@id":"https:\/\/cinegear.nl\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cinegear.nl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nl-NL"},{"@type":"Organization","@id":"https:\/\/cinegear.nl\/#organization","name":"Cinegear","url":"https:\/\/cinegear.nl\/","logo":{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/cinegear.nl\/#\/schema\/logo\/image\/","url":"https:\/\/cinegear.nl\/wp-content\/uploads\/2019\/12\/Transparent_Normal_Logo.jpg","contentUrl":"https:\/\/cinegear.nl\/wp-content\/uploads\/2019\/12\/Transparent_Normal_Logo.jpg","width":858,"height":782,"caption":"Cinegear"},"image":{"@id":"https:\/\/cinegear.nl\/#\/schema\/logo\/image\/"}}]}},"brands":[{"id":10145,"name":"Nanlux","slug":"nanlux"}],"_links":{"self":[{"href":"https:\/\/cinegear.nl\/nl\/wp-json\/wp\/v2\/product\/117430","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cinegear.nl\/nl\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/cinegear.nl\/nl\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cinegear.nl\/nl\/wp-json\/wp\/v2\/media\/117440"}],"wp:attachment":[{"href":"https:\/\/cinegear.nl\/nl\/wp-json\/wp\/v2\/media?parent=117430"}],"wp:term":[{"taxonomy":"pwb-brand","embeddable":true,"href":"https:\/\/cinegear.nl\/nl\/wp-json\/wp\/v2\/pwb-brand?post=117430"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/cinegear.nl\/nl\/wp-json\/wp\/v2\/product_cat?post=117430"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/cinegear.nl\/nl\/wp-json\/wp\/v2\/product_tag?post=117430"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}