{"id":127409,"date":"2026-09-02T10:51:36","date_gmt":"2026-09-02T08:51:36","guid":{"rendered":"https:\/\/cinegear.nl\/product\/mid49-universal-arri-hot-shoe-1-4-20-and-3-8-16\/"},"modified":"2026-09-02T10:51:36","modified_gmt":"2026-09-02T08:51:36","slug":"mid49-universal-arri-hot-shoe-1-4-20-and-3-8-16","status":"publish","type":"product","link":"https:\/\/cinegear.nl\/de\/produkt\/mid49-universal-arri-hot-shoe-1-4-20-and-3-8-16\/","title":{"rendered":"MID49 Universal ARRI Hot Shoe (1\/4-20 and 3\/8-16)"},"content":{"rendered":"<div class=\"row\"  id=\"row-612054296\">\n\n\t<div id=\"col-876240710\" class=\"col medium-2 small-12 large-2\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div id=\"text-3242798843\" class=\"text\">\n\t\t\n<h3><strong>\u00dcberblick<\/strong><\/h3>\n\t\t\n<style>\n#text-3242798843 {\n  font-size: 1.2rem;\n}\n@media (min-width:550px) {\n  #text-3242798843 {\n    font-size: 1rem;\n  }\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-876240710 > .col-inner {\n  padding: 0px 0px 0px 0px;\n  margin: 0px 0px -20px 0px;\n}\n@media (min-width:550px) {\n  #col-876240710 > .col-inner {\n    padding: 0px 0px 0px 0px;\n    margin: 0px 0px 0px 0px;\n  }\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-390497474\" class=\"col medium-10 small-12 large-10\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div id=\"text-3856894966\" class=\"text\">\n\t\t\n<p>The MID49 Universal ARRI Hot Shoe adapts ARRI threads to a cold shoe mounting slot. It includes 1\/4&quot;-20 and 3\/8&quot;-16 ARRI locating screws for compatibility with mounting components.<\/p>\n<p>The integrated locating pin positions can be adjusted with a T6 wrench or a flathead screwdriver.<\/p>\n\t\t\n<style>\n#text-3856894966 {\n  font-size: 0.9rem;\n}\n@media (min-width:550px) {\n  #text-3856894966 {\n    font-size: 1rem;\n  }\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-390497474 > .col-inner {\n  padding: 0px 0px 0px 0px;\n  margin: 0px 0px -30px 0px;\n}\n@media (min-width:550px) {\n  #col-390497474 > .col-inner {\n    padding: 0px 0px 0px 0px;\n    margin: 0px 0px 0px 0px;\n  }\n}\n<\/style>\n\t<\/div>\n\n\t\n\n<style>\n#row-612054296 > .col > .col-inner {\n  padding: 0px 0px 0px 0px;\n}\n@media (min-width:550px) {\n  #row-612054296 > .col > .col-inner {\n    padding: 0px 0px 10px 0px;\n  }\n}\n<\/style>\n<\/div>\n<div class=\"is-divider divider clearfix\" style=\"max-width:1600px;height:2px;\"><\/div>\n<div class=\"row\"  id=\"row-1315945560\">\n\n\t<div id=\"col-1556830832\" class=\"col medium-2 small-12 large-2\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div id=\"text-3014603714\" class=\"text\">\n\t\t\n<h3><strong>Features<\/strong><\/h3>\n\t\t\n<style>\n#text-3014603714 {\n  font-size: 1.2rem;\n}\n@media (min-width:550px) {\n  #text-3014603714 {\n    font-size: 1rem;\n  }\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1556830832 > .col-inner {\n  padding: 0px 0px 0px 0px;\n  margin: 7px 0px -20px 0px;\n}\n@media (min-width:550px) {\n  #col-1556830832 > .col-inner {\n    padding: 0px 0px 0px 0px;\n    margin: 0px 0px 0px 0px;\n  }\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-410630427\" class=\"col medium-10 small-12 large-10\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div id=\"text-3948389129\" class=\"text\">\n\t\t\n<ul>\n<li>Includes 1\/4&quot;-20 ARRI locating screw<\/li>\n<li>Includes 3\/8&quot;-16 ARRI locating screw<\/li>\n<li>Integrated locating pin positions can be changed using a T6 wrench or flathead screwdriver<\/li>\n<\/ul>\n\t\t\n<style>\n#text-3948389129 {\n  font-size: 0.9rem;\n}\n@media (min-width:550px) {\n  #text-3948389129 {\n    font-size: 1rem;\n  }\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-410630427 > .col-inner {\n  padding: 0px 0px 0px 0px;\n  margin: 0px 0px -30px 0px;\n}\n@media (min-width:550px) {\n  #col-410630427 > .col-inner {\n    padding: 0px 0px 0px 0px;\n    margin: 0px 0px 0px 0px;\n  }\n}\n<\/style>\n\t<\/div>\n\n\t\n\n<style>\n#row-1315945560 > .col > .col-inner {\n  padding: 0px 0px 0px 0px;\n}\n@media (min-width:550px) {\n  #row-1315945560 > .col > .col-inner {\n    padding: 30px 0px 10px 0px;\n  }\n}\n<\/style>\n<\/div>\n<div class=\"is-divider divider clearfix\" style=\"max-width:1600px;height:2px;\"><\/div>\n<div class=\"row\"  id=\"row-1599023569\">\n\n\t<div id=\"col-2058653215\" class=\"col medium-2 small-12 large-2\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div id=\"text-3974293352\" class=\"text\">\n\t\t\n<h3><strong>Included<br \/>\n<\/strong><\/h3>\n\t\t\n<style>\n#text-3974293352 {\n  font-size: 1.2rem;\n}\n@media (min-width:550px) {\n  #text-3974293352 {\n    font-size: 1rem;\n  }\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-2058653215 > .col-inner {\n  padding: 0px 0px 0px 0px;\n  margin: 7px 0px -20px 0px;\n}\n@media (min-width:550px) {\n  #col-2058653215 > .col-inner {\n    padding: 0px 0px 0px 0px;\n    margin: 0px 0px 0px 0px;\n  }\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-1932460433\" class=\"col medium-10 small-12 large-10\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div id=\"text-3766038623\" class=\"text\">\n\t\t\n<ul>\n<li>MID49 Universal ARRI Cold Shoe Mount<\/li>\n<li>1\/4&quot;-20 ARRI Locating Screw<\/li>\n<li>3\/8&quot;-16 ARRI Locating Screw<\/li>\n<\/ul>\n\t\t\n<style>\n#text-3766038623 {\n  font-size: 0.9rem;\n}\n@media (min-width:550px) {\n  #text-3766038623 {\n    font-size: 1rem;\n  }\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1932460433 > .col-inner {\n  padding: 0px 0px 0px 0px;\n  margin: 0px 0px -30px 0px;\n}\n@media (min-width:550px) {\n  #col-1932460433 > .col-inner {\n    padding: 0px 0px 0px 0px;\n    margin: 0px 0px 0px 0px;\n  }\n}\n<\/style>\n\t<\/div>\n\n\t\n\n<style>\n#row-1599023569 > .col > .col-inner {\n  padding: 0px 0px 0px 0px;\n}\n@media (min-width:550px) {\n  #row-1599023569 > .col > .col-inner {\n    padding: 30px 0px 10px 0px;\n  }\n}\n<\/style>\n<\/div>\n<div class=\"is-divider divider clearfix\" style=\"max-width:1600px;height:2px;\"><\/div>\n<div class=\"row\"  id=\"row-1260556693\">\n\n\t<div id=\"col-660375304\" class=\"col medium-2 small-12 large-2\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div id=\"text-3361093852\" class=\"text\">\n\t\t\n<h3><strong>Specifications<\/strong><\/h3>\n\t\t\n<style>\n#text-3361093852 {\n  font-size: 1.2rem;\n}\n@media (min-width:550px) {\n  #text-3361093852 {\n    font-size: 1rem;\n  }\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-660375304 > .col-inner {\n  padding: 0px 0px 0px 0px;\n  margin: 7px 0px -20px 0px;\n}\n@media (min-width:550px) {\n  #col-660375304 > .col-inner {\n    padding: 0px 0px 0px 0px;\n    margin: 0px 0px 0px 0px;\n  }\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-603647632\" class=\"col medium-10 small-12 large-10\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div id=\"text-2689317636\" class=\"text\">\n\t\t\n<table>\n<tbody>\n<tr>\n<th>Mounting<\/th>\n<td>Cage Mount: Included 1\/4&quot;-20 Male Screw , Included 3\/8&quot;-16 Male Screw , Cold Shoe<\/td>\n<\/tr>\n<tr>\n<th>Load Capacity<\/th>\n<td>Not Specified by Manufacturer<\/td>\n<\/tr>\n<tr>\n<th>Color<\/th>\n<td>Black<\/td>\n<\/tr>\n<tr>\n<th>Adjustments<\/th>\n<td>Fixed<\/td>\n<\/tr>\n<tr>\n<th>Package Weight<\/th>\n<td>0.07 lb \/ 0.03 kg<\/td>\n<\/tr>\n<tr>\n<th>Box Dimensions (LxWxH)<\/th>\n<td>3.55 x 2 x 0.7&quot; \/ 9.02 x 5.08 x 1.78 cm<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n\t\t\n<style>\n#text-2689317636 {\n  font-size: 0.9rem;\n}\n@media (min-width:550px) {\n  #text-2689317636 {\n    font-size: 1rem;\n  }\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-603647632 > .col-inner {\n  padding: 0px 0px 0px 0px;\n  margin: 0px 0px 0px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n<style>\n#row-1260556693 > .col > .col-inner {\n  padding: 0px 0px 0px 0px;\n}\n@media (min-width:550px) {\n  #row-1260556693 > .col > .col-inner {\n    padding: 30px 0px 10px 0px;\n  }\n}\n<\/style>\n<\/div>","protected":false},"excerpt":{"rendered":"<ul>\n<li>1\/4&quot;-20 and 3\/8&quot;-16 ARRI Locating Screws<\/li>\n<li>Adapts Threads to Cold Shoe Mount<\/li>\n<li>Change Pin Positions via Wrench<\/li>\n<\/ul>","protected":false},"featured_media":127399,"template":"","meta":{"_acf_changed":false,"inline_featured_image":false},"pwb-brand":[14708],"product_cat":[10369],"product_tag":[],"class_list":{"0":"post-127409","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"pwb-brand-mid49","7":"product_cat-rig-accessories","8":"product_shipping_class-normal","10":"first","11":"onbackorder","12":"taxable","13":"shipping-taxable","14":"purchasable","15":"product-type-simple"},"acf":{"supplier":"mid49","buy_price":"20.299999999999997","last_sync":""},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v21.8 (Yoast SEO v24.3) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>MID49 Universal ARRI Hot Shoe (1\/4-20 and 3\/8-16) | Cinegear Amsterdam<\/title>\n<meta name=\"description\" content=\"1\/4&quot;-20 and 3\/8&quot;-16 ARRI Locating Screws Adapts Threads to Cold Shoe Mount Change Pin Positions via Wrench\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cinegear.nl\/de\/produkt\/mid49-universal-arri-hot-shoe-1-4-20-and-3-8-16\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"MID49 Universal ARRI Hot Shoe (1\/4-20 and 3\/8-16)\" \/>\n<meta property=\"og:description\" content=\"1\/4&quot;-20 and 3\/8&quot;-16 ARRI Locating Screws Adapts Threads to Cold Shoe Mount Change Pin Positions via Wrench\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cinegear.nl\/de\/produkt\/mid49-universal-arri-hot-shoe-1-4-20-and-3-8-16\/\" \/>\n<meta property=\"og:site_name\" content=\"Cinegear Amsterdam\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/cinegear.nl\/product\/mid49-universal-arri-hot-shoe-1-4-20-and-3-8-16\/\",\"url\":\"https:\/\/cinegear.nl\/product\/mid49-universal-arri-hot-shoe-1-4-20-and-3-8-16\/\",\"name\":\"MID49 Universal ARRI Hot Shoe (1\/4-20 and 3\/8-16) | Cinegear Amsterdam\",\"isPartOf\":{\"@id\":\"https:\/\/cinegear.nl\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/cinegear.nl\/product\/mid49-universal-arri-hot-shoe-1-4-20-and-3-8-16\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/cinegear.nl\/product\/mid49-universal-arri-hot-shoe-1-4-20-and-3-8-16\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/cinegear.nl\/wp-content\/uploads\/2026\/09\/MID49-Universal-ARRI-Hot-Shoe-1-4-20-and-3-8-16.jpg\",\"datePublished\":\"2026-09-02T08:51:36+00:00\",\"dateModified\":\"2026-09-02T08:51:36+00:00\",\"description\":\"1\/4&quot;-20 and 3\/8&quot;-16 ARRI Locating Screws Adapts Threads to Cold Shoe Mount Change Pin Positions via Wrench\",\"breadcrumb\":{\"@id\":\"https:\/\/cinegear.nl\/product\/mid49-universal-arri-hot-shoe-1-4-20-and-3-8-16\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/cinegear.nl\/product\/mid49-universal-arri-hot-shoe-1-4-20-and-3-8-16\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/cinegear.nl\/product\/mid49-universal-arri-hot-shoe-1-4-20-and-3-8-16\/#primaryimage\",\"url\":\"https:\/\/cinegear.nl\/wp-content\/uploads\/2026\/09\/MID49-Universal-ARRI-Hot-Shoe-1-4-20-and-3-8-16.jpg\",\"contentUrl\":\"https:\/\/cinegear.nl\/wp-content\/uploads\/2026\/09\/MID49-Universal-ARRI-Hot-Shoe-1-4-20-and-3-8-16.jpg\",\"width\":1950,\"height\":1950,\"caption\":\"MID49 Universal ARRI Hot Shoe (1\/4-20 and 3\/8-16)\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/cinegear.nl\/product\/mid49-universal-arri-hot-shoe-1-4-20-and-3-8-16\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/cinegear.nl\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Store\",\"item\":\"https:\/\/cinegear.nl\/product-category-kine-cameras\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"MID49 Universal ARRI Hot Shoe (1\/4-20 and 3\/8-16)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/cinegear.nl\/#website\",\"url\":\"https:\/\/cinegear.nl\/\",\"name\":\"Cinegear Amsterdam\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/cinegear.nl\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/cinegear.nl\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/cinegear.nl\/#organization\",\"name\":\"Cinegear\",\"url\":\"https:\/\/cinegear.nl\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/cinegear.nl\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/cinegear.nl\/wp-content\/uploads\/2019\/12\/Transparent_Normal_Logo.jpg\",\"contentUrl\":\"https:\/\/cinegear.nl\/wp-content\/uploads\/2019\/12\/Transparent_Normal_Logo.jpg\",\"width\":858,\"height\":782,\"caption\":\"Cinegear\"},\"image\":{\"@id\":\"https:\/\/cinegear.nl\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"MID49 Universal ARRI Hot Shoe (1\/4-20 and 3\/8-16) | Cinegear Amsterdam","description":"1\/4&quot;-20 and 3\/8&quot;-16 ARRI Locating Screws Adapts Threads to Cold Shoe Mount Change Pin Positions via Wrench","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cinegear.nl\/de\/produkt\/mid49-universal-arri-hot-shoe-1-4-20-and-3-8-16\/","og_locale":"de_DE","og_type":"article","og_title":"MID49 Universal ARRI Hot Shoe (1\/4-20 and 3\/8-16)","og_description":"1\/4&quot;-20 and 3\/8&quot;-16 ARRI Locating Screws Adapts Threads to Cold Shoe Mount Change Pin Positions via Wrench","og_url":"https:\/\/cinegear.nl\/de\/produkt\/mid49-universal-arri-hot-shoe-1-4-20-and-3-8-16\/","og_site_name":"Cinegear Amsterdam","twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/cinegear.nl\/product\/mid49-universal-arri-hot-shoe-1-4-20-and-3-8-16\/","url":"https:\/\/cinegear.nl\/product\/mid49-universal-arri-hot-shoe-1-4-20-and-3-8-16\/","name":"MID49 Universal ARRI Hot Shoe (1\/4-20 and 3\/8-16) | Cinegear Amsterdam","isPartOf":{"@id":"https:\/\/cinegear.nl\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cinegear.nl\/product\/mid49-universal-arri-hot-shoe-1-4-20-and-3-8-16\/#primaryimage"},"image":{"@id":"https:\/\/cinegear.nl\/product\/mid49-universal-arri-hot-shoe-1-4-20-and-3-8-16\/#primaryimage"},"thumbnailUrl":"https:\/\/cinegear.nl\/wp-content\/uploads\/2026\/09\/MID49-Universal-ARRI-Hot-Shoe-1-4-20-and-3-8-16.jpg","datePublished":"2026-09-02T08:51:36+00:00","dateModified":"2026-09-02T08:51:36+00:00","description":"1\/4&quot;-20 and 3\/8&quot;-16 ARRI Locating Screws Adapts Threads to Cold Shoe Mount Change Pin Positions via Wrench","breadcrumb":{"@id":"https:\/\/cinegear.nl\/product\/mid49-universal-arri-hot-shoe-1-4-20-and-3-8-16\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cinegear.nl\/product\/mid49-universal-arri-hot-shoe-1-4-20-and-3-8-16\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/cinegear.nl\/product\/mid49-universal-arri-hot-shoe-1-4-20-and-3-8-16\/#primaryimage","url":"https:\/\/cinegear.nl\/wp-content\/uploads\/2026\/09\/MID49-Universal-ARRI-Hot-Shoe-1-4-20-and-3-8-16.jpg","contentUrl":"https:\/\/cinegear.nl\/wp-content\/uploads\/2026\/09\/MID49-Universal-ARRI-Hot-Shoe-1-4-20-and-3-8-16.jpg","width":1950,"height":1950,"caption":"MID49 Universal ARRI Hot Shoe (1\/4-20 and 3\/8-16)"},{"@type":"BreadcrumbList","@id":"https:\/\/cinegear.nl\/product\/mid49-universal-arri-hot-shoe-1-4-20-and-3-8-16\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cinegear.nl\/"},{"@type":"ListItem","position":2,"name":"Store","item":"https:\/\/cinegear.nl\/product-category-kine-cameras\/"},{"@type":"ListItem","position":3,"name":"MID49 Universal ARRI Hot Shoe (1\/4-20 and 3\/8-16)"}]},{"@type":"WebSite","@id":"https:\/\/cinegear.nl\/#website","url":"https:\/\/cinegear.nl\/","name":"Cinegear Amsterdam","description":"","publisher":{"@id":"https:\/\/cinegear.nl\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cinegear.nl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/cinegear.nl\/#organization","name":"Cinegear","url":"https:\/\/cinegear.nl\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/cinegear.nl\/#\/schema\/logo\/image\/","url":"https:\/\/cinegear.nl\/wp-content\/uploads\/2019\/12\/Transparent_Normal_Logo.jpg","contentUrl":"https:\/\/cinegear.nl\/wp-content\/uploads\/2019\/12\/Transparent_Normal_Logo.jpg","width":858,"height":782,"caption":"Cinegear"},"image":{"@id":"https:\/\/cinegear.nl\/#\/schema\/logo\/image\/"}}]}},"brands":[{"id":14708,"name":"MID49","slug":"mid49"}],"_links":{"self":[{"href":"https:\/\/cinegear.nl\/de\/wp-json\/wp\/v2\/product\/127409","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cinegear.nl\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/cinegear.nl\/de\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cinegear.nl\/de\/wp-json\/wp\/v2\/media\/127399"}],"wp:attachment":[{"href":"https:\/\/cinegear.nl\/de\/wp-json\/wp\/v2\/media?parent=127409"}],"wp:term":[{"taxonomy":"pwb-brand","embeddable":true,"href":"https:\/\/cinegear.nl\/de\/wp-json\/wp\/v2\/pwb-brand?post=127409"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/cinegear.nl\/de\/wp-json\/wp\/v2\/product_cat?post=127409"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/cinegear.nl\/de\/wp-json\/wp\/v2\/product_tag?post=127409"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}